{"id":222,"date":"2023-01-04T11:03:54","date_gmt":"2023-01-04T10:03:54","guid":{"rendered":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/?p=222"},"modified":"2023-01-04T11:05:08","modified_gmt":"2023-01-04T10:05:08","slug":"liposuccion-poids-corporel","status":"publish","type":"post","link":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/liposuccion-poids-corporel\/","title":{"rendered":"Liposuccion et poids corporel : clarification"},"content":{"rendered":"<p style=\"text-align: justify;\">Le tissu adipeux est omnipr\u00e9sent dans notre corps, que ce soit \u00e0 la surface, sous la peau, ou dans nos organes internes. Ce sont souvent ces accumulations de graisse qui font partie des pr\u00e9occupations majeures des patients, hommes et femmes, qui, malgr\u00e9 un r\u00e9gime alimentaire contr\u00f4l\u00e9 et la pratique d&rsquo;exercices physiques, ne parviennent pas \u00e0 obtenir la silhouette souhait\u00e9e.<!--more--><\/p>\n<h2 style=\"text-align: justify;\">Qu&rsquo;est-ce que la liposuccion ?<\/h2>\n<p style=\"text-align: justify;\">La liposuccion est une intervention chirurgicale mod\u00e9r\u00e9ment invasive qui consiste \u00e0 r\u00e9duire l&rsquo;exc\u00e8s de tissu adipeux superficiel. Au cours de l&rsquo;intervention, on ins\u00e8re des canules de diff\u00e9rentes tailles et aux extr\u00e9mit\u00e9s de formes diverses qui, reli\u00e9es \u00e0 une source d&rsquo;aspiration, extraient la graisse de diff\u00e9rentes zones de notre corps.<\/p>\n<h2 style=\"text-align: justify;\">Liposuccion et anesth\u00e9sie locale<\/h2>\n<p style=\"text-align: justify;\">Il est tout \u00e0 fait possible de r\u00e9aliser une liposuccion sous anesth\u00e9sie locale (\u00e9ventuellement avec une l\u00e9g\u00e8re s\u00e9dation anesth\u00e9sique), \u00e0 condition que les zones \u00e0 traiter soient tr\u00e8s limit\u00e9es (par exemple les classiques poign\u00e9es d&rsquo;amour) et que le patient puisse tol\u00e9rer un l\u00e9ger inconfort pendant l&rsquo;injection de l&rsquo;anesth\u00e9sie. Dans tous les autres cas, lorsque l&rsquo;aspiration de la quantit\u00e9 de tissu adipeux est mod\u00e9r\u00e9ment \u00e9lev\u00e9e, il est conseill\u00e9 de soumettre le sujet \u00e0 une anesth\u00e9sie g\u00e9n\u00e9rale.<\/p>\n<h2 style=\"text-align: justify;\">Comment puis-je me d\u00e9barrasser des bourrelets \u00e0 long terme ?<\/h2>\n<p style=\"text-align: justify;\">Si les habitudes alimentaires d&rsquo;une personne sont mauvaises et qu&rsquo;en plus de ne pas manger correctement, elle ne pratique m\u00eame pas un minimum d&rsquo;activit\u00e9 physique, les fameux \u00ab\u00a0bourrelets\u00a0\u00bb ne dispara\u00eetront jamais compl\u00e8tement sur une longue p\u00e9riode. Certes, la liposuccion peut \u00e9liminer ces accumulations de graisse, mais si le patient, apr\u00e8s la liposuccion, continue \u00e0 avoir une mauvaise fa\u00e7on de s&rsquo;alimenter et de se maintenir en forme, la graisse r\u00e9appara\u00eetra dans un d\u00e9lai plus ou moins long.<\/p>\n<h2 style=\"text-align: justify;\">Quel poids pour faire une liposuccion\u00a0?<\/h2>\n<p style=\"text-align: justify;\">Commen\u00e7ons par un fait tr\u00e8s important : la graisse p\u00e8se beaucoup moins que ce que l&rsquo;on pourrait croire. En effet, le poids sp\u00e9cifique (c&rsquo;est-\u00e0-dire le gramme\/centim\u00e8tre cube) de la graisse est de 0,9. En d&rsquo;autres termes, le poids sp\u00e9cifique du muscle est de 1,1 et celui de l&rsquo;eau de 1. Il est donc facile de voir comment, m\u00eame si une quantit\u00e9 consid\u00e9rable de graisse est aspir\u00e9e, le poids du sujet ne variera pas beaucoup.<\/p>\n<p style=\"text-align: justify;\">C&rsquo;est pourquoi la liposuccion ou <a href=\"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/liposuccion-perdre-du-poids\/\">lipoaspiration n&rsquo;est pas une intervention chirurgicale pour perdre du poids<\/a>, mais un moyen de donner \u00e0 notre corps une forme plus harmonieuse et plus esth\u00e9tique.<\/p>\n<h2 style=\"text-align: justify;\">Qui peut subir une liposuccion ?<\/h2>\n<p style=\"text-align: justify;\">En principe, toute personne pr\u00e9sentant des d\u00e9p\u00f4ts graisseux localis\u00e9s peut subir une liposuccion. Cela dit, il y a des conditions \u00e0 prendre en compte afin de donner une indication pour la proc\u00e9dure. Un patient pr\u00e9sentant un IMC (indice de masse corporelle, c&rsquo;est-\u00e0-dire le rapport entre le poids et la taille \u00e0 la seconde) \u00e9lev\u00e9, 25 et plus, doit envisager de suivre un r\u00e9gime alimentaire sain et contr\u00f4l\u00e9 et de pratiquer une activit\u00e9 physique avant de subir une liposuccion. En outre, un patient qui, en plus des d\u00e9p\u00f4ts graisseux, pr\u00e9sente \u00e9galement une laxit\u00e9 cutan\u00e9e, g\u00e9n\u00e9ralement dans la r\u00e9gion abdominale, pourrait r\u00e9soudre le probl\u00e8me des d\u00e9p\u00f4ts graisseux avec la liposuccion mais aggraver le probl\u00e8me de la peau l\u00e2che. Dans ce cas, une chirurgie combin\u00e9e de liposuccion et d&rsquo;abdominoplastie serait indiqu\u00e9e, c&rsquo;est-\u00e0-dire une op\u00e9ration capable de retendre la peau et les muscles de la r\u00e9gion abdominale. Enfin, les contre-indications absolues \u00e0 la liposuccion sont des conditions de sant\u00e9 globales qui pourraient mettre le patient en danger pendant l&rsquo;op\u00e9ration ou les femmes enceintes ou en p\u00e9riode de post-partum imm\u00e9diat.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Le tissu adipeux est omnipr\u00e9sent dans notre corps, que ce soit \u00e0 la surface, sous la peau, ou dans nos organes internes. Ce sont souvent ces accumulations de graisse qui font partie des pr\u00e9occupations majeures des patients, hommes et femmes, qui, malgr\u00e9 un r\u00e9gime alimentaire contr\u00f4l\u00e9 et la pratique d&rsquo;exercices physiques, ne parviennent pas \u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":223,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Liposuccion et poids corporel : questions et r\u00e9ponses<\/title>\n<meta name=\"description\" content=\"Liposuccion et poids corporel : questions et r\u00e9ponses sur le poids auquel le patient peut faire une liposuccion.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/liposuccion-poids-corporel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Liposuccion et poids corporel : questions et r\u00e9ponses\" \/>\n<meta property=\"og:description\" content=\"Liposuccion et poids corporel : questions et r\u00e9ponses sur le poids auquel le patient peut faire une liposuccion.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/liposuccion-poids-corporel\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-04T10:03:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-04T10:05:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/wp-content\/uploads\/2023\/01\/Liposuccion-et-poids-corporel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"758\" \/>\n\t<meta property=\"og:image:height\" content=\"505\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"R\u00e9daction Medespoir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@dsh_mertnlip-fr\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"R\u00e9daction Medespoir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/liposuccion-poids-corporel\/\",\"url\":\"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/liposuccion-poids-corporel\/\",\"name\":\"Liposuccion et poids corporel : questions et r\u00e9ponses\",\"isPartOf\":{\"@id\":\"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/#website\"},\"datePublished\":\"2023-01-04T10:03:54+00:00\",\"dateModified\":\"2023-01-04T10:05:08+00:00\",\"author\":{\"@id\":\"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/#\/schema\/person\/c653c6bb376124e914e75d1e4be5540a\"},\"description\":\"Liposuccion et poids corporel : questions et r\u00e9ponses sur le poids auquel le patient peut faire une liposuccion.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/liposuccion-poids-corporel\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/liposuccion-poids-corporel\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/liposuccion-poids-corporel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Liposuccion et poids corporel : clarification\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/#website\",\"url\":\"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/\",\"name\":\"Blog\",\"description\":\"Tout savoir sur la liposuccion\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/#\/schema\/person\/c653c6bb376124e914e75d1e4be5540a\",\"name\":\"R\u00e9daction Medespoir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/853d4ae87f978c14d7d2e9056c315b19?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/853d4ae87f978c14d7d2e9056c315b19?s=96&d=mm&r=g\",\"caption\":\"R\u00e9daction Medespoir\"},\"sameAs\":[\"https:\/\/medespoir-tunisie-liposuccion.fr\/blog\",\"https:\/\/twitter.com\/dsh_mertnlip-fr\"],\"url\":\"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/author\/dsh_mertnlip-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Liposuccion et poids corporel : questions et r\u00e9ponses","description":"Liposuccion et poids corporel : questions et r\u00e9ponses sur le poids auquel le patient peut faire une liposuccion.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/liposuccion-poids-corporel\/","og_locale":"fr_FR","og_type":"article","og_title":"Liposuccion et poids corporel : questions et r\u00e9ponses","og_description":"Liposuccion et poids corporel : questions et r\u00e9ponses sur le poids auquel le patient peut faire une liposuccion.","og_url":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/liposuccion-poids-corporel\/","og_site_name":"Blog","article_published_time":"2023-01-04T10:03:54+00:00","article_modified_time":"2023-01-04T10:05:08+00:00","og_image":[{"width":758,"height":505,"url":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/wp-content\/uploads\/2023\/01\/Liposuccion-et-poids-corporel.jpg","type":"image\/jpeg"}],"author":"R\u00e9daction Medespoir","twitter_card":"summary_large_image","twitter_creator":"@dsh_mertnlip-fr","twitter_misc":{"\u00c9crit par":"R\u00e9daction Medespoir","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/liposuccion-poids-corporel\/","url":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/liposuccion-poids-corporel\/","name":"Liposuccion et poids corporel : questions et r\u00e9ponses","isPartOf":{"@id":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/#website"},"datePublished":"2023-01-04T10:03:54+00:00","dateModified":"2023-01-04T10:05:08+00:00","author":{"@id":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/#\/schema\/person\/c653c6bb376124e914e75d1e4be5540a"},"description":"Liposuccion et poids corporel : questions et r\u00e9ponses sur le poids auquel le patient peut faire une liposuccion.","breadcrumb":{"@id":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/liposuccion-poids-corporel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/liposuccion-poids-corporel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/liposuccion-poids-corporel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Liposuccion et poids corporel : clarification"}]},{"@type":"WebSite","@id":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/#website","url":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/","name":"Blog","description":"Tout savoir sur la liposuccion","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/#\/schema\/person\/c653c6bb376124e914e75d1e4be5540a","name":"R\u00e9daction Medespoir","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/853d4ae87f978c14d7d2e9056c315b19?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/853d4ae87f978c14d7d2e9056c315b19?s=96&d=mm&r=g","caption":"R\u00e9daction Medespoir"},"sameAs":["https:\/\/medespoir-tunisie-liposuccion.fr\/blog","https:\/\/twitter.com\/dsh_mertnlip-fr"],"url":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/author\/dsh_mertnlip-fr\/"}]}},"_links":{"self":[{"href":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/wp-json\/wp\/v2\/posts\/222"}],"collection":[{"href":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/wp-json\/wp\/v2\/comments?post=222"}],"version-history":[{"count":1,"href":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/wp-json\/wp\/v2\/posts\/222\/revisions"}],"predecessor-version":[{"id":224,"href":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/wp-json\/wp\/v2\/posts\/222\/revisions\/224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/wp-json\/wp\/v2\/media\/223"}],"wp:attachment":[{"href":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/wp-json\/wp\/v2\/media?parent=222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/wp-json\/wp\/v2\/categories?post=222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medespoir-tunisie-liposuccion.fr\/blog\/wp-json\/wp\/v2\/tags?post=222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}